{"id":599,"date":"2021-04-12T18:34:12","date_gmt":"2021-04-12T16:34:12","guid":{"rendered":"https:\/\/comunicacionyescuela.es\/2021\/?p=599"},"modified":"2021-04-12T18:34:12","modified_gmt":"2021-04-12T16:34:12","slug":"jornada-literaria-con-la-escritora-ana-alonso-y-la-investigadora-carmen-martinez-rodriguez","status":"publish","type":"post","link":"https:\/\/www.comunicacionyescuela.es\/2021\/actualidad-del-foro\/jornada-literaria-con-la-escritora-ana-alonso-y-la-investigadora-carmen-martinez-rodriguez\/","title":{"rendered":"Jornada literaria con la escritora Ana Alonso y la investigadora Carmen Mart\u00ednez Rodr\u00edguez"},"content":{"rendered":"<p>La escritora Ana Alonso y la investigadora Carmen Rodr\u00edguez participar\u00e1n en una doble jornada literaria con los alumnos del Colegio Jovellanos y del IES Elisa y Luis Villamil en torno a la novela Historia de una rosa (Ed. Anaya, 2019) y que ha sido le\u00edda por los alumnos de 5\u00ba y 6\u00ba de Educaci\u00f3n Primaria de ambos centros.<br \/>\nA las diez de la ma\u00f1ana estar\u00e1n con los estudiantes del Colegio Jovellanos y a las 12 con los  del IES Elisa y Luis Villamil. Esta actividad se enmarca en el proyecto \u201cMujer y sociedad en el siglo XXI. Mujeres que cambian el mundo\u201dy ser\u00e1 retransmitida en directo a trav\u00e9s de internet  por los siguientes canales:<br \/>\n\u2022\tP\u00e1gina web del proyecto: https:\/\/www.comunicacionyescuela.es\/2021\/<br \/>\n\u2022\tCanal de YouTube al que es posible suscribirse suscribiros: https:\/\/www.youtube.com\/channel\/UCAxtXbvXAtI8-kZyW1W1JgQ<br \/>\n\u2022\tCuenta de Facebook: https:\/\/www.youtube.com\/channel\/UCAxtXbvXAtI8-kZyW1W1JgQ<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La escritora Ana Alonso y la investigadora Carmen Rodr\u00edguez participar\u00e1n en una doble jornada literaria con los alumnos del Colegio Jovellanos y del IES Elisa y Luis Villamil en torno &#8230; <a title=\"Jornada literaria con la escritora Ana Alonso y la investigadora Carmen Mart\u00ednez Rodr\u00edguez\" class=\"read-more\" href=\"https:\/\/www.comunicacionyescuela.es\/2021\/actualidad-del-foro\/jornada-literaria-con-la-escritora-ana-alonso-y-la-investigadora-carmen-martinez-rodriguez\/\" aria-label=\"Leer m\u00e1s sobre Jornada literaria con la escritora Ana Alonso y la investigadora Carmen Mart\u00ednez Rodr\u00edguez\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":3,"featured_media":600,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts\/599"}],"collection":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/comments?post=599"}],"version-history":[{"count":1,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts\/599\/revisions"}],"predecessor-version":[{"id":601,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts\/599\/revisions\/601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/media\/600"}],"wp:attachment":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/media?parent=599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/categories?post=599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/tags?post=599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}