{"id":576,"date":"2021-04-12T08:58:49","date_gmt":"2021-04-12T06:58:49","guid":{"rendered":"https:\/\/comunicacionyescuela.es\/2021\/?p=576"},"modified":"2021-11-23T20:14:49","modified_gmt":"2021-11-23T19:14:49","slug":"el-comercio","status":"publish","type":"post","link":"https:\/\/www.comunicacionyescuela.es\/2021\/noticias-en-prensa\/el-comercio\/","title":{"rendered":"El comercio"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.elcomercio.es\/asturias\/occidente\/renunciar-formacion-vivir-20211120000836-ntvo.html\" target=\"_blank\" rel=\"noopener\">\u00abNo tenemos que renunciar a nada en la formaci\u00f3n por vivir en un pueblo\u00bb<\/a><\/p>\n<p><a href=\"https:\/\/www.elcomercio.es\/asturias\/occidente\/pandemia-deja-gran-20211118000611-ntvo.html\" target=\"_blank\" rel=\"noopener\">\u00abLa pandemia deja una gran desigualdad, la distribuci\u00f3n de las vacunas es injusta\u00bb<\/a><\/p>\n<p><a href=\"https:\/\/www.elcomercio.es\/asturias\/occidente\/estudiantes-varios-institutos-20211105001408-ntvo.html\" target=\"_blank\" rel=\"noopener\">Mil estudiantes de varios institutos, conectados por la obra de Miguel Delibes<\/a><\/p>\n<p><a href=\"https:\/\/www.elcomercio.es\/asturias\/occidente\/alumnos-elisa-luis-20211028000851-ntvo.html\" target=\"_blank\" rel=\"noopener\">Los alumnos del IES Elisa y Luis Villamil aprenden las t\u00e9cnicas para realizar una RCP<\/a><\/p>\n<p><a href=\"https:\/\/www.elcomercio.es\/asturias\/occidente\/cardiologa-beatriz-diaz-20211020000711-ntvo.html\" target=\"_blank\" rel=\"noopener\">La cardi\u00f3loga Beatriz D\u00edaz da las claves para llevar una vida sana en el Foro Comunicaci\u00f3n y Escuela<\/a><\/p>\n<p><a href=\"https:\/\/www.elcomercio.es\/asturias\/occidente\/queremos-empresa-movilidad-20211015000803-ntvo.html\" target=\"_blank\" rel=\"noopener\">\u00abQueremos ser una empresa de movilidad sostenible, multimodal y conectada\u00bb<\/a><\/p>\n<p><a href=\"https:\/\/www.elcomercio.es\/asturias\/occidente\/barbon-medio-rural-20211008000831-ntvo.html\" target=\"_blank\" rel=\"noopener\">Barb\u00f3n: \u00abNuestro medio rural tiene que ser un lugar para vivir y trabajar\u00bb<\/a><\/p>\n<p><a href=\"https:\/\/www.elcomercio.es\/tecnologia\/internet\/irene-cano-directora-general-facebook-espana-portugal-importante-incentivemos-ninas-20211006000930-ntvo.html#vca=eng-leidas&amp;vmc=amp&amp;vso=elcomercio&amp;vli=leidas-5\" target=\"_blank\" rel=\"noopener\">Irene Cano, directora General de Facebook en Espa\u00f1a y Portugal: \u00abEs importante que incentivemos a las ni\u00f1as a arriesgarse\u00bb<\/a><\/p>\n<p><a href=\"https:\/\/www.elcomercio.es\/asturias\/occidente\/fundacion-margarita-salas-20211001001647-ntvo.html\" target=\"_blank\" rel=\"noopener\">La Fundaci\u00f3n Margarita Salas trabajar\u00e1 para captar talento cient\u00edfico en las zonas rurales<\/a><\/p>\n<p><a href=\"https:\/\/www.elcomercio.es\/asturias\/occidente\/competitividad-vendra-mano-20210623001125-ntvo.html\">\u00abLa competitividad vendr\u00e1 de la mano de la innovaci\u00f3n y de la transformaci\u00f3n digital\u00bb<\/a><\/p>\n<p><a href=\"https:\/\/www.elcomercio.es\/asturias\/occidente\/alumnos-elisa-luis-villamil-junta-diputados-20210529000913-ntvo.html\">Alumnos del IES Elisa y Luis Villamil descubren la Junta de mano de los diputados<\/a><\/p>\n<p><a href=\"https:\/\/www.elcomercio.es\/asturias\/occidente\/union-europea-puede-definir-paz-oportunidades-solidaridad-20210522000733-ntvo.html?ref=https:%2F%2Fwww.google.es%2F\">\u00abLa Uni\u00f3n Europea se puede definir en tres palabras: paz, oportunidades y solidaridad\u00bb<\/a><\/p>\n<p><a href=\"https:\/\/www.elcomercio.es\/asturias\/occidente\/principio-pandemia-europa-20210511002851-ntvo.html\">\u00abAl principio de la pandemia Europa no actu\u00f3 bien, fue un caos. Pero aprendi\u00f3 la lecci\u00f3n\u00bb<\/a><\/p>\n<p><a href=\"https:\/\/www.elcomercio.es\/asturias\/laboratorio-politica-diferentes-20210413000957-ntvo.html\">\u00abEl laboratorio y la pol\u00edtica no son muy diferentes\u00bb<\/a><\/p>\n<p><a href=\"https:\/\/www.elcomercio.es\/asturias\/occidente\/foro-comunicacion-escuela-20210409000901-ntvo.html\">Foro Comunicaci\u00f3n y Escuela pone el foco en el papel de la mujer en la sociedad actual<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; \u00abNo tenemos que renunciar a nada en la formaci\u00f3n por vivir en un pueblo\u00bb \u00abLa pandemia deja una gran desigualdad, la distribuci\u00f3n de las vacunas es injusta\u00bb Mil estudiantes &#8230; <a title=\"El comercio\" class=\"read-more\" href=\"https:\/\/www.comunicacionyescuela.es\/2021\/noticias-en-prensa\/el-comercio\/\" aria-label=\"Leer m\u00e1s sobre El comercio\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[14],"tags":[],"_links":{"self":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts\/576"}],"collection":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/comments?post=576"}],"version-history":[{"count":17,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts\/576\/revisions"}],"predecessor-version":[{"id":2485,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts\/576\/revisions\/2485"}],"wp:attachment":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/media?parent=576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/categories?post=576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/tags?post=576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}