{"id":2494,"date":"2021-11-23T20:24:39","date_gmt":"2021-11-23T19:24:39","guid":{"rendered":"https:\/\/comunicacionyescuela.es\/2021\/?p=2494"},"modified":"2021-11-23T20:24:39","modified_gmt":"2021-11-23T19:24:39","slug":"presentado-el-libro-las-aventuras-de-nube","status":"publish","type":"post","link":"https:\/\/www.comunicacionyescuela.es\/2021\/actualidad-del-foro\/presentado-el-libro-las-aventuras-de-nube\/","title":{"rendered":"Presentado el libro Las aventuras de Nube"},"content":{"rendered":"<p>La presentaci\u00f3n del libro de relatos Las aventuras de Nube se convirti\u00f3 en uno de los momentos m\u00e1s emocionantes del acto de clausura de este XIII Foro Comunicaci\u00f3n y Escuela. Intervinieron la escritora, Ana Alcolea, que escribi\u00f3 el pr\u00f3logo, as\u00ed como la ilustradora, Lulas Somoza que es a su vez profesora del IES Elisa y Luis Villamil. Por parte de las entidades patrocinadoras de la publicaci\u00f3n tomaron la palabra Alfredo Zornoza de Banco Sabadell y \u00c1ngel Moraleda de Fundaci\u00f3n EDP. Sin duda, el momento m\u00e1s emotivo tuvo lugar con la intervenci\u00f3n de los representantes de los alumnos autores de los relatos que manifestaron la gran satisfacci\u00f3n que sent\u00edan por haber participado en ese proyecto literario. Terminado el acto de clausura se procedi\u00f3 a la tradicional firma de libros.<\/p>\n<p>Cabe destacar que este proyecto literario supone un nuevo hito del Foro Comunicaci\u00f3n y Escuela y es la primera vez que estudiantes del IES Elisa y Luis Villamil ven publicado un libro de este tipo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presentaci\u00f3n del libro de relatos Las aventuras de Nube se convirti\u00f3 en uno de los momentos m\u00e1s emocionantes del acto de clausura de este XIII Foro Comunicaci\u00f3n y Escuela. &#8230; <a title=\"Presentado el libro Las aventuras de Nube\" class=\"read-more\" href=\"https:\/\/www.comunicacionyescuela.es\/2021\/actualidad-del-foro\/presentado-el-libro-las-aventuras-de-nube\/\" aria-label=\"Leer m\u00e1s sobre Presentado el libro Las aventuras de Nube\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":2495,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts\/2494"}],"collection":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/comments?post=2494"}],"version-history":[{"count":1,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts\/2494\/revisions"}],"predecessor-version":[{"id":2496,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts\/2494\/revisions\/2496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/media\/2495"}],"wp:attachment":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/media?parent=2494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/categories?post=2494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/tags?post=2494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}