{"id":2488,"date":"2021-11-23T20:19:24","date_gmt":"2021-11-23T19:19:24","guid":{"rendered":"https:\/\/comunicacionyescuela.es\/2021\/?p=2488"},"modified":"2021-11-23T20:19:24","modified_gmt":"2021-11-23T19:19:24","slug":"ana-santos-la-biblioteca-nacional-atesora-mas-de-trescientos-anos-de-historia","status":"publish","type":"post","link":"https:\/\/www.comunicacionyescuela.es\/2021\/actualidad-del-foro\/ana-santos-la-biblioteca-nacional-atesora-mas-de-trescientos-anos-de-historia\/","title":{"rendered":"Ana Santos: \u201cLa Biblioteca Nacional atesora m\u00e1s de trescientos a\u00f1os de historia\u201d"},"content":{"rendered":"<p>La directora de la Biblioteca Nacional de Espa\u00f1a, Ana Santos, fue la encargada de pronunciar la \u00faltima conferencia de este XIII Foro Comunicaci\u00f3n y Escuela, aunque el acto esta vez s\u00ed fue presencial.<\/p>\n<p>Durante su intervenci\u00f3n hizo una encendida defensa de del labor de la bibliotecas y, en especial, de las bibliotecas rurales. Adem\u00e1s, explic\u00f3 con detalle a los alumnos los proyectos m\u00e1s novedosos de la Biblioteca Nacional de Espa\u00f1a, as\u00ed como de los fondos de los que dispone la entidad.<\/p>\n<p>Antes de finalizar su conferencia, Ana Santos, invit\u00f3 a los estudiantes a fomentar el esp\u00edritu cr\u00edtico y a investigar sobre todo aquello que les pueda aportar informaci\u00f3n, y les insisti\u00f3 en que sean asiduos visitantes de las bibliotecas.<\/p>\n<p>Posteriormente, contest\u00f3 a las numerosas preguntas que formularon los alumnos de 2\u00ba de Bachillerato que participaron en este acto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La directora de la Biblioteca Nacional de Espa\u00f1a, Ana Santos, fue la encargada de pronunciar la \u00faltima conferencia de este XIII Foro Comunicaci\u00f3n y Escuela, aunque el acto esta vez &#8230; <a title=\"Ana Santos: \u201cLa Biblioteca Nacional atesora m\u00e1s de trescientos a\u00f1os de historia\u201d\" class=\"read-more\" href=\"https:\/\/www.comunicacionyescuela.es\/2021\/actualidad-del-foro\/ana-santos-la-biblioteca-nacional-atesora-mas-de-trescientos-anos-de-historia\/\" aria-label=\"Leer m\u00e1s sobre Ana Santos: \u201cLa Biblioteca Nacional atesora m\u00e1s de trescientos a\u00f1os de historia\u201d\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":2489,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts\/2488"}],"collection":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/comments?post=2488"}],"version-history":[{"count":1,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts\/2488\/revisions"}],"predecessor-version":[{"id":2490,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts\/2488\/revisions\/2490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/media\/2489"}],"wp:attachment":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/media?parent=2488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/categories?post=2488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/tags?post=2488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}