{"id":1144,"date":"2021-05-11T07:36:03","date_gmt":"2021-05-11T05:36:03","guid":{"rendered":"https:\/\/comunicacionyescuela.es\/2021\/?p=1144"},"modified":"2021-05-11T07:36:03","modified_gmt":"2021-05-11T05:36:03","slug":"maria-luisa-muga-el-parlamento-europeo-tiene-abundantes-propuestas-para-acercarse-a-los-jovenes","status":"publish","type":"post","link":"https:\/\/www.comunicacionyescuela.es\/2021\/actualidad-del-foro\/maria-luisa-muga-el-parlamento-europeo-tiene-abundantes-propuestas-para-acercarse-a-los-jovenes\/","title":{"rendered":"Mar\u00eda Luisa Muga: \u201cEl Parlamento Europeo tiene abundantes propuestas para acercarse a los j\u00f3venes\u201d"},"content":{"rendered":"<p>La funcionaria del Parlamento Europeo, Mar\u00eda Luisa Muga, manifest\u00f3 durante su intervenci\u00f3n en este XIII Foro Comunicaci\u00f3n y Escuela, Edici\u00f3n Online, que el Parlamento Europeo busca la participaci\u00f3n de los j\u00f3venes, para lo cual dispone de abundantes proyectos y programas con tal fin. La administradora y conferenciante del Servicio de Visitas y Seminarios del Parlamento Europeo hizo un detallado recorrido sobre lo qu\u00e9 es y c\u00f3mo funciona esta instituci\u00f3n: historia de la UE, pa\u00edses miembros en las diferentes etapas, n\u00famero de diputados, lenguas utilizadas, partidos con representaci\u00f3n en el Parlamento, mecanismos para proponer leyes, etc\u00e9tera fueron algunos de los temas sobre los que disert\u00f3 en su conferencia dirigida a los alumnos de 1\u00ba de Bachillerato del IES Elisa y Luis Villamil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La funcionaria del Parlamento Europeo, Mar\u00eda Luisa Muga, manifest\u00f3 durante su intervenci\u00f3n en este XIII Foro Comunicaci\u00f3n y Escuela, Edici\u00f3n Online, que el Parlamento Europeo busca la participaci\u00f3n de los &#8230; <a title=\"Mar\u00eda Luisa Muga: \u201cEl Parlamento Europeo tiene abundantes propuestas para acercarse a los j\u00f3venes\u201d\" class=\"read-more\" href=\"https:\/\/www.comunicacionyescuela.es\/2021\/actualidad-del-foro\/maria-luisa-muga-el-parlamento-europeo-tiene-abundantes-propuestas-para-acercarse-a-los-jovenes\/\" aria-label=\"Leer m\u00e1s sobre Mar\u00eda Luisa Muga: \u201cEl Parlamento Europeo tiene abundantes propuestas para acercarse a los j\u00f3venes\u201d\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":3,"featured_media":1145,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts\/1144"}],"collection":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/comments?post=1144"}],"version-history":[{"count":1,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts\/1144\/revisions"}],"predecessor-version":[{"id":1146,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/posts\/1144\/revisions\/1146"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/media\/1145"}],"wp:attachment":[{"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/media?parent=1144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/categories?post=1144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2021\/wp-json\/wp\/v2\/tags?post=1144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}