﻿{"id":671,"date":"2019-04-01T07:43:47","date_gmt":"2019-04-01T05:43:47","guid":{"rendered":"http:\/\/www.comunicacionyescuela.es\/2019\/?p=671"},"modified":"2019-04-01T07:43:47","modified_gmt":"2019-04-01T05:43:47","slug":"nando-lopez-la-clave-para-que-un-libro-enganche-es-la-emocion","status":"publish","type":"post","link":"https:\/\/www.comunicacionyescuela.es\/2019\/actualidad-del-foro\/nando-lopez-la-clave-para-que-un-libro-enganche-es-la-emocion\/","title":{"rendered":"Nando L\u00f3pez: \u201cLa clave para que un libro enganche es la emoci\u00f3n\u201d"},"content":{"rendered":"<p>El escritor, Nando L\u00f3pez, una de las voces m\u00e1s relevantes de la literatura infantil y juvenil actual dijo a los estudiantes de Vegadeo en el encuentro con autor desarrollado en este XI Foro Comunicaci\u00f3n y Escuela que una de las claves para que un libro enganche es que consiga despertar en el lector una intensa emoci\u00f3n. Nando L\u00f3pez, que viaj\u00f3 desde Madrid para encontrarse con los estudiantes veigue\u00f1os, es el autor de las novelas: <em>El reino de las tres lunas <\/em>y<em> Los nombres del fuego<\/em>, ambos libros le\u00eddos por los alumnos de 2\u00ba y 4\u00ba de Educaci\u00f3n Secundaria. El autor transmiti\u00f3 a los j\u00f3venes lectores la importancia que debe tener la lectura y la literatura a la hora de ayudarnos a afrontar los propios procesos internos que vivimos en nuestra vida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El escritor, Nando L\u00f3pez, una de las voces m\u00e1s relevantes de la literatura infantil y juvenil actual dijo a los estudiantes de Vegadeo en el encuentro con autor desarrollado en &#8230; <a title=\"Nando L\u00f3pez: \u201cLa clave para que un libro enganche es la emoci\u00f3n\u201d\" class=\"read-more\" href=\"https:\/\/www.comunicacionyescuela.es\/2019\/actualidad-del-foro\/nando-lopez-la-clave-para-que-un-libro-enganche-es-la-emocion\/\" aria-label=\"Leer m\u00e1s sobre Nando L\u00f3pez: \u201cLa clave para que un libro enganche es la emoci\u00f3n\u201d\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":672,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/posts\/671"}],"collection":[{"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/comments?post=671"}],"version-history":[{"count":1,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/posts\/671\/revisions"}],"predecessor-version":[{"id":673,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/posts\/671\/revisions\/673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/media\/672"}],"wp:attachment":[{"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/media?parent=671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/categories?post=671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/tags?post=671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}