﻿{"id":4584,"date":"2019-10-23T08:04:49","date_gmt":"2019-10-23T06:04:49","guid":{"rendered":"http:\/\/www.comunicacionyescuela.es\/2019\/?p=4584"},"modified":"2019-10-23T08:04:49","modified_gmt":"2019-10-23T06:04:49","slug":"continuan-los-actos-de-clausura-con-la-conferencia-de-la-catedratica-angeles-menendez-patterson","status":"publish","type":"post","link":"https:\/\/www.comunicacionyescuela.es\/2019\/actualidad-del-foro\/continuan-los-actos-de-clausura-con-la-conferencia-de-la-catedratica-angeles-menendez-patterson\/","title":{"rendered":"Contin\u00faan los actos de clausura con la conferencia de la catedr\u00e1tica \u00c1ngeles Men\u00e9ndez Patterson"},"content":{"rendered":"<p>La catedr\u00e1tica de Fisiolog\u00eda de la Universidad de Oviedo, \u00c1ngeles Men\u00e9ndez Patterson, impartir\u00e1 la conferencia: \u201cPautas para conseguir una alimentaci\u00f3n equilibrada a partir de la dieta\u201d&nbsp; el pr\u00f3ximo jueves, 24 de octubre, en el sal\u00f3n de actos del IES Elisa y Luis Villamil. La conferencia est\u00e1 dirigida a los alumnos de 2\u00ba de Educaci\u00f3n Secundaria y se enmarca dentro del proyecto \u201cEscuela y salud\u201d incluido en este XI Foro Comunicaci\u00f3n y Escuela\u201d, as\u00ed como en la programaci\u00f3n de clausura de esta und\u00e9cima edici\u00f3n. La catedr\u00e1tica \u00c1ngeles Patterson es una refutada investigadora y especialista en nutrici\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La catedr\u00e1tica de Fisiolog\u00eda de la Universidad de Oviedo, \u00c1ngeles Men\u00e9ndez Patterson, impartir\u00e1 la conferencia: \u201cPautas para conseguir una alimentaci\u00f3n equilibrada a partir de la dieta\u201d&nbsp; el pr\u00f3ximo jueves, 24 &#8230; <a title=\"Contin\u00faan los actos de clausura con la conferencia de la catedr\u00e1tica \u00c1ngeles Men\u00e9ndez Patterson\" class=\"read-more\" href=\"https:\/\/www.comunicacionyescuela.es\/2019\/actualidad-del-foro\/continuan-los-actos-de-clausura-con-la-conferencia-de-la-catedratica-angeles-menendez-patterson\/\" aria-label=\"Leer m\u00e1s sobre Contin\u00faan los actos de clausura con la conferencia de la catedr\u00e1tica \u00c1ngeles Men\u00e9ndez Patterson\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":4585,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/posts\/4584"}],"collection":[{"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/comments?post=4584"}],"version-history":[{"count":1,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/posts\/4584\/revisions"}],"predecessor-version":[{"id":4586,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/posts\/4584\/revisions\/4586"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/media\/4585"}],"wp:attachment":[{"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/media?parent=4584"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/categories?post=4584"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/tags?post=4584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}