﻿{"id":3917,"date":"2019-09-18T10:02:01","date_gmt":"2019-09-18T08:02:01","guid":{"rendered":"http:\/\/www.comunicacionyescuela.es\/2019\/?p=3917"},"modified":"2019-09-18T10:02:01","modified_gmt":"2019-09-18T08:02:01","slug":"jornada-dedicada-a-la-guardia-civil-2","status":"publish","type":"post","link":"https:\/\/www.comunicacionyescuela.es\/2019\/actualidad-del-foro\/jornada-dedicada-a-la-guardia-civil-2\/","title":{"rendered":"Jornada dedicada a la Guardia Civil"},"content":{"rendered":"<p>Adem\u00e1s de la conferencia sobre la Guardia Civil como salida profesional, esta jornada dedicada en este XI Foro Comunicaci\u00f3n y Escuela a esta instituci\u00f3n se completa con una espectacular exhibici\u00f3n de especialidades de la Guardia Civil: acu\u00e1ticas, cineg\u00e9ticas, explosivos, seguridad ciudadana, laboratorios, SEPRONA, etc. Igualmente participar\u00e1n medios a\u00e9reos con la presencia de dos helic\u00f3pteros. Todo un despliegue sin precedentes en el occidente de Asturias gracias a la colaboraci\u00f3n de la Comandancia de la Guardia Civil de Oviedo.<\/p>\n<p>Esta exhibici\u00f3n contar\u00e1 con la participaci\u00f3n de m\u00e1s de 800 escolares de diversos centros educativos del occidente de Asturias: CRA Oscos, CRA Occidente, CRA R\u00eda del Eo, Colegio Jovellanos, Colegio La Paloma, CRA Tapia-Castropol, IES Carmen y Severo Ochoa, Fundaci\u00f3n EDES e IES Elisa Y Luis Villamil. Los actos son abiertos al p\u00fablico en general.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s de la conferencia sobre la Guardia Civil como salida profesional, esta jornada dedicada en este XI Foro Comunicaci\u00f3n y Escuela a esta instituci\u00f3n se completa con una espectacular exhibici\u00f3n &#8230; <a title=\"Jornada dedicada a la Guardia Civil\" class=\"read-more\" href=\"https:\/\/www.comunicacionyescuela.es\/2019\/actualidad-del-foro\/jornada-dedicada-a-la-guardia-civil-2\/\" aria-label=\"Leer m\u00e1s sobre Jornada dedicada a la Guardia Civil\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":3918,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/posts\/3917"}],"collection":[{"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/comments?post=3917"}],"version-history":[{"count":1,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/posts\/3917\/revisions"}],"predecessor-version":[{"id":3919,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/posts\/3917\/revisions\/3919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/media\/3918"}],"wp:attachment":[{"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/media?parent=3917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/categories?post=3917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/tags?post=3917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}