﻿{"id":2117,"date":"2019-05-04T19:26:34","date_gmt":"2019-05-04T17:26:34","guid":{"rendered":"http:\/\/www.comunicacionyescuela.es\/2019\/?p=2117"},"modified":"2019-05-04T19:26:34","modified_gmt":"2019-05-04T17:26:34","slug":"manuel-sanchez-ocana-la-salud-bucodental-es-clave-para-evitar-enfermedades","status":"publish","type":"post","link":"https:\/\/www.comunicacionyescuela.es\/2019\/actualidad-del-foro\/manuel-sanchez-ocana-la-salud-bucodental-es-clave-para-evitar-enfermedades\/","title":{"rendered":"Manuel S\u00e1nchez-Oca\u00f1a: \u201cLa salud bucodental es clave para evitar enfermedades\u201d"},"content":{"rendered":"<p>Los m\u00e9dicos especialistas en salud bucodental: Manuel S\u00e1nchez-Oca\u00f1a Olay y Bel\u00e9n S\u00e1nchez-Oca\u00f1a Olay impartieron la conferencia titulada: \u201cLa salud bucodental en la infancia y la jueventud\u201d a los alumnos de 1\u00ba de Educaci\u00f3n Secundaria el IES Elisa y Luis Villamil. Esta conferencia estaba enmarcada en el proyecto \u201cEscuela y salud\u201d de este XI Foro Comunicaci\u00f3n y Escuela. Durante su intervenci\u00f3n, ambos especialistas, expusieron a los estudiantes la importancia de cuidar la salud bucodental desde muy peque\u00f1os y la trascendencia que esto tiene en la prevenci\u00f3n de otras patolog\u00edas. En este sentido explicaron la necesidad de las revisiones de la boca, el correcto lavado de los dientes y lengua o c\u00f3mo aprender t\u00e9cnicas para un correcto cepillado de la boca. Al finalizar la charla los alumnos asistentes hicieron numerosos preguntas.<\/p>\n<p><strong>Foto: De izquierda a derecha: Julio Quesada, jefe del Departamento de Orientaci\u00f3n; Manuel S\u00e1nchez Oca\u00f1a-Olay, odont\u00f3logo; Bel\u00e9n S\u00e1nchez-Oca\u00f1a Olay, odont\u00f3loga y la profesora de Ciencias Naturales, Chus Millares.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los m\u00e9dicos especialistas en salud bucodental: Manuel S\u00e1nchez-Oca\u00f1a Olay y Bel\u00e9n S\u00e1nchez-Oca\u00f1a Olay impartieron la conferencia titulada: \u201cLa salud bucodental en la infancia y la jueventud\u201d a los alumnos de &#8230; <a title=\"Manuel S\u00e1nchez-Oca\u00f1a: \u201cLa salud bucodental es clave para evitar enfermedades\u201d\" class=\"read-more\" href=\"https:\/\/www.comunicacionyescuela.es\/2019\/actualidad-del-foro\/manuel-sanchez-ocana-la-salud-bucodental-es-clave-para-evitar-enfermedades\/\" aria-label=\"Leer m\u00e1s sobre Manuel S\u00e1nchez-Oca\u00f1a: \u201cLa salud bucodental es clave para evitar enfermedades\u201d\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":2118,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/posts\/2117"}],"collection":[{"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/comments?post=2117"}],"version-history":[{"count":1,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/posts\/2117\/revisions"}],"predecessor-version":[{"id":2119,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/posts\/2117\/revisions\/2119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/media\/2118"}],"wp:attachment":[{"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/media?parent=2117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/categories?post=2117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comunicacionyescuela.es\/2019\/wp-json\/wp\/v2\/tags?post=2117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}